{"id":686913,"date":"2022-03-03T14:18:12","date_gmt":"2022-03-03T13:18:12","guid":{"rendered":"https:\/\/apuestasfree.com\/?p=686913"},"modified":"2022-03-03T14:23:03","modified_gmt":"2022-03-03T13:23:03","slug":"rushbet-atletico-nacional-vs-independiente-medellin","status":"publish","type":"post","link":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/","title":{"rendered":"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!"},"content":{"rendered":"\n<p>Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar <a href=\"https:\/\/recor.to\/rushbet\" rel=\"nofollow noopener sponsored\">\u00a1Abre tu cuenta ahora!<\/a><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/recor.to\/rushbet\" rel=\"nofollow noopener sponsored\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg\" alt=\"rushbet atl\u00e9tico nacional vs independiente medell\u00edn\" class=\"wp-image-686915\" srcset=\"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg 1024w, https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-300x169.jpg 300w, https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-768x432.jpg 768w, https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-realiza-tu-apuesta-en-rushbet-para-el-partido-atl-tico-nacional-vs-independiente-medell-n\">Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn<\/h2>\n\n\n\n<p>El pr\u00f3ximo domingo 6 de marzo <strong>Atl\u00e9tico Nacional recibe a Independiente de Medell\u00edn<\/strong> por la d\u00e9cima jornada de la Liga Betplay Dimayor. Reg\u00edstrate en Rushbet y vive al m\u00e1ximo el cl\u00e1sico Paisa con 20.000 COP de regalo <a href=\"https:\/\/recor.to\/rushbet\" rel=\"nofollow noopener sponsored\">\u00a1Reg\u00edstrate ya!<\/a><\/p>\n<p>La presente edici\u00f3n del Cl\u00e1sico Paisa encuentra a los protagonistas en una pelea palmo a palmo por las posiciones altas del campeonato. En este sentido, <strong><em>La M\u00e1quina Verde\u00a0<\/em>se ubica tercera en la clasificaci\u00f3n con tres victorias, una derrota y un empate en los \u00faltimos cinco enfrentamientos.<\/strong><\/p>\n<p>Por su parte, <strong>el DIM, a tan solo dos puntos de su eterno rival, se encuentra cuarto en la tabla con tres victorias y dos derrotas<\/strong> en los \u00faltimos cinco partidos disputados. \u00bfQui\u00e9n se quedar\u00e1 con el cl\u00e1sico?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-bono-de-bienvenida-rushbet-100-hasta-20-000-cop-para-apostar\">Bono de bienvenida Rushbet: 100% hasta 20.000 COP para apostar<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400;\">Si todav\u00eda no te registraste en Rushbet, te recomendamos hacerlo hoy mismo para recibir el bono de bienvenida del 100% hasta 20.000 COP para las apuestas deportivas. Lo \u00fanico que tienes que hacer es abrir una cuenta y depositar con el <\/span><b>c\u00f3digo de bono 100MAS<\/b><span style=\"font-weight: 400;\"> para duplicar tu saldo. En caso de tener alguna duda al respecto, te recomendamos leer: <\/span><a href=\"https:\/\/apuestasfree.com\/co\/rushbet-como-ingresar-dinero\/\"><span style=\"font-weight: 400;\">Todo sobre el bono de bienvenida Rushbet.<\/span><\/a><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link\" style=\"border-radius:0px\"><strong><em>\u00a1RECLAMA 20.000 COP AHORA!<\/em><\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><b>T\u00e9rminos y condiciones principales:<\/b><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Requisito de apuesta x5 el valor del bono.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Contribuyen las apuestas sencillas con cuota 2.00 o superior.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Cuentan para la liberaci\u00f3n del bono los juegos de Casino tipo Slot, Video Bingo y Slingo, juegos de Cartas, Blackjack y Varios cuentan con un 20% y los juegos tipo Ruleta con un 10%<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">No cuentan para la liberaci\u00f3n del bono las apuestas combinadas, anuladas y cash out.<\/span><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar \u00a1Abre tu cuenta ahora! Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn El pr\u00f3ximo domingo 6 de marzo Atl\u00e9tico Nacional recibe a Independiente de Medell\u00edn por la d\u00e9cima jornada &#8230; <a title=\"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!\" class=\"read-more\" href=\"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/\" aria-label=\"Read more about Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","af_slider_source":"legacy","footnotes":""},"categories":[32732],"tags":[],"class_list":["post-686913","post","type-post","status-publish","format-standard","hentry","category-uncategorized-co"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!<\/title>\n<meta name=\"description\" content=\"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!\" \/>\n<meta property=\"og:description\" content=\"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/\" \/>\n<meta property=\"og:site_name\" content=\"ApuestasFree\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-03T13:18:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-03T13:23:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg\" \/>\n<meta name=\"author\" content=\"afree\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"afree\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/\"},\"author\":{\"name\":\"afree\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/person\\\/1df4523287e409932205c28649f3ba5f\"},\"headline\":\"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!\",\"datePublished\":\"2022-03-03T13:18:12+00:00\",\"dateModified\":\"2022-03-03T13:23:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/\"},\"wordCount\":335,\"publisher\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg\",\"articleSection\":[\"Uncategorized @co\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/\",\"name\":\"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg\",\"datePublished\":\"2022-03-03T13:18:12+00:00\",\"dateModified\":\"2022-03-03T13:23:03+00:00\",\"description\":\"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg\",\"contentUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/rushbet-atletico-nacional-vs-independiente-medellin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/\",\"name\":\"ApuestasFree\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#organization\",\"name\":\"ApuestasFree\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/afree_logo.png\",\"contentUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/afree_logo.png\",\"width\":106,\"height\":50,\"caption\":\"ApuestasFree\"},\"image\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/person\\\/1df4523287e409932205c28649f3ba5f\",\"name\":\"afree\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/author\\\/afree\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!","description":"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/","og_locale":"es_ES","og_type":"article","og_title":"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!","og_description":"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar.","og_url":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/","og_site_name":"ApuestasFree","article_published_time":"2022-03-03T13:18:12+00:00","article_modified_time":"2022-03-03T13:23:03+00:00","og_image":[{"url":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg","type":"","width":"","height":""}],"author":"afree","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"afree","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#article","isPartOf":{"@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/"},"author":{"name":"afree","@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/person\/1df4523287e409932205c28649f3ba5f"},"headline":"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!","datePublished":"2022-03-03T13:18:12+00:00","dateModified":"2022-03-03T13:23:03+00:00","mainEntityOfPage":{"@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/"},"wordCount":335,"publisher":{"@id":"https:\/\/apuestasfree.com\/co\/#organization"},"image":{"@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#primaryimage"},"thumbnailUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg","articleSection":["Uncategorized @co"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/","url":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/","name":"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!","isPartOf":{"@id":"https:\/\/apuestasfree.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#primaryimage"},"image":{"@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#primaryimage"},"thumbnailUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg","datePublished":"2022-03-03T13:18:12+00:00","dateModified":"2022-03-03T13:23:03+00:00","description":"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar.","breadcrumb":{"@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#primaryimage","url":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg","contentUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2022\/03\/rushbet-atletico-nacional-vs-independiente-medellin-1024x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/apuestasfree.com\/co\/rushbet-atletico-nacional-vs-independiente-medellin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/apuestasfree.com\/co\/"},{"@type":"ListItem","position":2,"name":"Rushbet Atl\u00e9tico Nacional vs Independiente Medell\u00edn \u00a1Apuesta ahora!"}]},{"@type":"WebSite","@id":"https:\/\/apuestasfree.com\/co\/#website","url":"https:\/\/apuestasfree.com\/co\/","name":"ApuestasFree","description":"","publisher":{"@id":"https:\/\/apuestasfree.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apuestasfree.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/apuestasfree.com\/co\/#organization","name":"ApuestasFree","url":"https:\/\/apuestasfree.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2019\/06\/afree_logo.png","contentUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2019\/06\/afree_logo.png","width":106,"height":50,"caption":"ApuestasFree"},"image":{"@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/person\/1df4523287e409932205c28649f3ba5f","name":"afree","url":"https:\/\/apuestasfree.com\/co\/author\/afree\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"afree","author_link":"https:\/\/apuestasfree.com\/co\/author\/afree\/"},"uagb_comment_info":0,"uagb_excerpt":"Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn. Reg\u00edstrate hoy y recibe $20.000 COP para apostar \u00a1Abre tu cuenta ahora! Realiza tu apuesta en Rushbet para el partido Atl\u00e9tico Nacional vs Independiente Medell\u00edn El pr\u00f3ximo domingo 6 de marzo Atl\u00e9tico Nacional recibe a Independiente de Medell\u00edn por la d\u00e9cima jornada&hellip;","_links":{"self":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/posts\/686913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/comments?post=686913"}],"version-history":[{"count":0,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/posts\/686913\/revisions"}],"wp:attachment":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/media?parent=686913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/categories?post=686913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/tags?post=686913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}