{"id":255196,"date":"2020-10-23T10:00:52","date_gmt":"2020-10-23T08:00:52","guid":{"rendered":"https:\/\/apuestasfree.com\/?p=255196"},"modified":"2022-12-06T05:47:10","modified_gmt":"2022-12-06T04:47:10","slug":"codere-fakir","status":"publish","type":"post","link":"https:\/\/apuestasfree.com\/co\/codere-fakir\/","title":{"rendered":"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere"},"content":{"rendered":"<p>Hoy, en <a href=\"https:\/\/apuestasfree.com\/co\" target=\"_blank\" rel=\"noopener noreferrer\">ApuestasFree<\/a>, te traemos para que juegues de<strong> forma totalmente gratuita la demo de la slot Fakir<\/strong> que puedes encontrar en <a href=\"https:\/\/recor.to\/coderecocasino\" target=\"_blank\" rel=\"noopener noreferrer nofollow sponsored\">Codere<\/a>. Se trata de una slot con la que viajar\u00e1s a antiguo oriente medio en busca de grandes tesoros.<\/p>\n<p>Aqu\u00ed, te daremos todas las <strong>pistas y nociones necesarias sobre la slot fakir de <a href=\"https:\/\/recor.to\/coderecocasino\" target=\"_blank\" rel=\"noopener noreferrer nofollow sponsored\">Codere<\/a>,<\/strong> para que as\u00ed, cuando acabes de jugar a la demo, puedas <strong>poner en juego tu dinero sabiendo que cuentas con bastantes posibilidades de descubrir los grandes tesoros que hay escondidos en oriente.<\/strong><br \/>\n<iframe id=\"outerIframeWrapperBody\" style=\"width: 100%; min-height: -webkit-fill-available;\" src=\"https:\/\/online.codere.com.co\/promoLoadDisplay?key=ej0xNDU3MjE2MCZsPTE0NTcyMTIyJnA9MzcxMA%3D%3D\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n<script>\n        function outerIframeFunction() {\n            var isMobile = navigator.userAgent.toLowerCase().match(\/mobile\/i);\n            if (isMobile) {\n                var heightsMobile = window.innerHeight;\n                document.getElementById(\"outerBody\").style.height = heightsMobile + \"px\";\n                document.getElementById(\"outerIframeWrapperBody\").style.height = heightsMobile + \"px\"; } }\n        function outerIframeResize() {\n            window.location.reload(); }\n    <\/script><\/p>\n<h2>La slot Fakir de Codere<\/h2>\n<p>Ya sabes que la <strong>tem\u00e1tica de la slot Fakir <a href=\"https:\/\/recor.to\/coderecocasino\" target=\"_blank\" rel=\"noopener noreferrer nofollow sponsored\">de Codere<\/a> trata sobre el antiguo oriente<\/strong> y los tesoros y recompensas que este albergaba. Hablamos de una m\u00e1quina que cuenta con <strong>5 rodillos o tambores, con un RTP de en torno al 95,75% y con nada menos que la sorprendente cifra de 243 l\u00edneas de pago<\/strong>. Se trata de una m\u00e1quina en la que podr\u00e1s optar a conseguir el<strong> bote progresivo o Jackpot.<\/strong><\/p>\n<p>Encontramos en total<strong> 9 s\u00edmbolos de pago<\/strong>, entre los que se encuentran:<strong> Fakir, La Asistente, La Cobra, La Flauta, El Pu\u00f1al, las letras A, K, J, Q y los n\u00fameros 8 y 10<\/strong>. Adem\u00e1s tambi\u00e9n encontramos dos s\u00edmbolos adicionales,<strong> La Flor de Loto, que act\u00faa como WILD (comod\u00edn) y Los Tejos (Bonus que activa el juego de Fakir)<\/strong>.<\/p>\n<p>Jugar a esta m\u00e1quina no tiene ning\u00fan misterio puesto que cuenta \u00fanicamente con<strong> 4 botones: &#8220;Menos&#8221; y &#8220;M\u00e1s&#8221; para bajar o subir la apuesta &#8220;Girar Auto&#8221; y &#8220;girar&#8221; para jugar.<\/strong><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-260457\" src=\"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png\" alt=\"Fakir Codere\" width=\"800\" height=\"453\" srcset=\"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png 1005w, https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere-300x170.png 300w, https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere-768x435.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<h3>Juegos adicionales de la slot Fakir<\/h3>\n<p>Los <strong><a href=\"https:\/\/recor.to\/coderecocasino\" target=\"_blank\" rel=\"noopener noreferrer nofollow sponsored\">juegos adicionales gratuitos<\/a> de la slot Fakir de Codere se activar\u00e1n si se consiguen al menos 3 s\u00edmbolos de &#8220;Bono&#8221; en la rejilla para obtener 8 giros gratis y tejos para el bono.<\/strong><\/p>\n<p>Durante tus tiradas, cada s\u00edmbolo de bonificaci\u00f3n te da tejos adicionales. Cuando los tengas, l\u00e1nzalos todos y recoge los beneficios para tus giros gratis. Los beneficios de lanzar tejos son: G<strong>anancias, giros gratis, multiplicadores para tiros gratis y la activaci\u00f3n del Passing Wild (con el que se reemplazar\u00e1n nada menos que 2 rodillos por comodines.<\/strong><\/p>\n<p>Si consigues acumular 3 estrellas, tendr\u00e1s la <strong>opci\u00f3n de jugar el Jackpot para intentar llevarte el bote progresivo de la slot Fakir.<\/strong><\/p>\n<h2>Consigue hasta $100.000 en cashback con tu primer dep\u00f3sito<\/h2>\n<p>Si te ha gustado la<strong> experiencia de jugar a la demo de la slot Fakir de Codere te recomendamos que pruebes ahora con el <a href=\"https:\/\/recor.to\/coderecocasino\" target=\"_blank\" rel=\"noopener noreferrer nofollow sponsored\">juego real de Codere<\/a><\/strong>, ya que de esa manera tendr\u00e1s la <strong>oportunidad de conseguir ganancias reales<\/strong>. <a href=\"https:\/\/recor.to\/coderecocasino\" target=\"_blank\" rel=\"noopener noreferrer nofollow sponsored\">Registr\u00e1ndote en Codere<\/a>, tus primeros <strong>giros los practicar\u00e1s de forma segura, ya que si juegas en las 24 horas posteriores a tu primer dep\u00f3sito y pierdes, Codere te devolver\u00e1 hasta $100.000<\/strong>. Si quieres toda la informaci\u00f3n sobre la promoci\u00f3n de bienvenida de Codere, picha en este enlace.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy, en ApuestasFree, te traemos para que juegues de forma totalmente gratuita la demo de la slot Fakir que puedes encontrar en Codere. Se trata de una slot con la que viajar\u00e1s a antiguo oriente medio en busca de grandes tesoros. Aqu\u00ed, te daremos todas las pistas y nociones necesarias sobre la slot fakir de &#8230; <a title=\"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere\" class=\"read-more\" href=\"https:\/\/apuestasfree.com\/co\/codere-fakir\/\" aria-label=\"Read more about Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":10162,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","af_slider_source":"legacy","footnotes":""},"categories":[32470],"tags":[],"class_list":["post-255196","post","type-post","status-publish","format-standard","hentry","category-codere-3"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere<\/title>\n<meta name=\"description\" content=\"P\u00e1salo en grande jugando de forma gratuita a la slot Fakir de Codere. Pru\u00e9bala y disfruta de una de las mejores slots de Codere.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apuestasfree.com\/co\/codere-fakir\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere\" \/>\n<meta property=\"og:description\" content=\"P\u00e1salo en grande jugando de forma gratuita a la slot Fakir de Codere. Pru\u00e9bala y disfruta de una de las mejores slots de Codere.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apuestasfree.com\/co\/codere-fakir\/\" \/>\n<meta property=\"og:site_name\" content=\"ApuestasFree\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-23T08:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-06T04:47:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png\" \/>\n<meta name=\"author\" content=\"jon\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jon\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/\"},\"author\":{\"name\":\"jon\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/person\\\/9750d75e29ef80cbe71a542aa9698d40\"},\"headline\":\"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere\",\"datePublished\":\"2020-10-23T08:00:52+00:00\",\"dateModified\":\"2022-12-06T04:47:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/\"},\"wordCount\":499,\"publisher\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/slot-fakir-codere.png\",\"articleSection\":[\"Codere\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/\",\"name\":\"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/slot-fakir-codere.png\",\"datePublished\":\"2020-10-23T08:00:52+00:00\",\"dateModified\":\"2022-12-06T04:47:10+00:00\",\"description\":\"P\u00e1salo en grande jugando de forma gratuita a la slot Fakir de Codere. Pru\u00e9bala y disfruta de una de las mejores slots de Codere.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/slot-fakir-codere.png\",\"contentUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/slot-fakir-codere.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/codere-fakir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/\",\"name\":\"ApuestasFree\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#organization\",\"name\":\"ApuestasFree\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/afree_logo.png\",\"contentUrl\":\"https:\\\/\\\/apuestasfree.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/afree_logo.png\",\"width\":106,\"height\":50,\"caption\":\"ApuestasFree\"},\"image\":{\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/#\\\/schema\\\/person\\\/9750d75e29ef80cbe71a542aa9698d40\",\"name\":\"jon\",\"url\":\"https:\\\/\\\/apuestasfree.com\\\/co\\\/author\\\/jon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere","description":"P\u00e1salo en grande jugando de forma gratuita a la slot Fakir de Codere. Pru\u00e9bala y disfruta de una de las mejores slots de Codere.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apuestasfree.com\/co\/codere-fakir\/","og_locale":"es_ES","og_type":"article","og_title":"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere","og_description":"P\u00e1salo en grande jugando de forma gratuita a la slot Fakir de Codere. Pru\u00e9bala y disfruta de una de las mejores slots de Codere.","og_url":"https:\/\/apuestasfree.com\/co\/codere-fakir\/","og_site_name":"ApuestasFree","article_published_time":"2020-10-23T08:00:52+00:00","article_modified_time":"2022-12-06T04:47:10+00:00","og_image":[{"url":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png","type":"","width":"","height":""}],"author":"jon","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jon","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#article","isPartOf":{"@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/"},"author":{"name":"jon","@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/person\/9750d75e29ef80cbe71a542aa9698d40"},"headline":"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere","datePublished":"2020-10-23T08:00:52+00:00","dateModified":"2022-12-06T04:47:10+00:00","mainEntityOfPage":{"@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/"},"wordCount":499,"publisher":{"@id":"https:\/\/apuestasfree.com\/co\/#organization"},"image":{"@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#primaryimage"},"thumbnailUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png","articleSection":["Codere"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/","url":"https:\/\/apuestasfree.com\/co\/codere-fakir\/","name":"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere","isPartOf":{"@id":"https:\/\/apuestasfree.com\/co\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#primaryimage"},"image":{"@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#primaryimage"},"thumbnailUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png","datePublished":"2020-10-23T08:00:52+00:00","dateModified":"2022-12-06T04:47:10+00:00","description":"P\u00e1salo en grande jugando de forma gratuita a la slot Fakir de Codere. Pru\u00e9bala y disfruta de una de las mejores slots de Codere.","breadcrumb":{"@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apuestasfree.com\/co\/codere-fakir\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#primaryimage","url":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png","contentUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2020\/10\/slot-fakir-codere.png"},{"@type":"BreadcrumbList","@id":"https:\/\/apuestasfree.com\/co\/codere-fakir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/apuestasfree.com\/co\/"},{"@type":"ListItem","position":2,"name":"Juega gratis con la versi\u00f3n demo de la slot Fakir de Codere"}]},{"@type":"WebSite","@id":"https:\/\/apuestasfree.com\/co\/#website","url":"https:\/\/apuestasfree.com\/co\/","name":"ApuestasFree","description":"","publisher":{"@id":"https:\/\/apuestasfree.com\/co\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apuestasfree.com\/co\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Organization","@id":"https:\/\/apuestasfree.com\/co\/#organization","name":"ApuestasFree","url":"https:\/\/apuestasfree.com\/co\/","logo":{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/logo\/image\/","url":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2019\/06\/afree_logo.png","contentUrl":"https:\/\/apuestasfree.com\/wp-content\/uploads\/2019\/06\/afree_logo.png","width":106,"height":50,"caption":"ApuestasFree"},"image":{"@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/apuestasfree.com\/co\/#\/schema\/person\/9750d75e29ef80cbe71a542aa9698d40","name":"jon","url":"https:\/\/apuestasfree.com\/co\/author\/jon\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"jon","author_link":"https:\/\/apuestasfree.com\/co\/author\/jon\/"},"uagb_comment_info":0,"uagb_excerpt":"Hoy, en ApuestasFree, te traemos para que juegues de forma totalmente gratuita la demo de la slot Fakir que puedes encontrar en Codere. Se trata de una slot con la que viajar\u00e1s a antiguo oriente medio en busca de grandes tesoros. Aqu\u00ed, te daremos todas las pistas y nociones necesarias sobre la slot fakir de&hellip;","_links":{"self":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/posts\/255196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/users\/10162"}],"replies":[{"embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/comments?post=255196"}],"version-history":[{"count":0,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/posts\/255196\/revisions"}],"wp:attachment":[{"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/media?parent=255196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/categories?post=255196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apuestasfree.com\/co\/wp-json\/wp\/v2\/tags?post=255196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}